{"id":153,"date":"2021-05-21T17:56:09","date_gmt":"2021-05-21T20:56:09","guid":{"rendered":"http:\/\/www.pconstrutora.com.br\/blog\/?p=153"},"modified":"2022-02-25T17:50:26","modified_gmt":"2022-02-25T20:50:26","slug":"arquitetura-melhor-dicas","status":"publish","type":"post","link":"https:\/\/www.pconstrutora.com.br\/blog\/arquitetura-melhor-dicas\/","title":{"rendered":"Estilos arquitet\u00f4nicos para construir uma casa: Qual a melhor op\u00e7\u00e3o?"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"530\" src=\"https:\/\/www.pconstrutora.com.br\/blog\/wp-content\/uploads\/2021\/05\/architecture-project-finishes-and-style-1024x530.jpg\" alt=\"\" class=\"wp-image-154\" srcset=\"https:\/\/www.pconstrutora.com.br\/blog\/wp-content\/uploads\/2021\/05\/architecture-project-finishes-and-style-1024x530.jpg 1024w, https:\/\/www.pconstrutora.com.br\/blog\/wp-content\/uploads\/2021\/05\/architecture-project-finishes-and-style-300x155.jpg 300w, https:\/\/www.pconstrutora.com.br\/blog\/wp-content\/uploads\/2021\/05\/architecture-project-finishes-and-style-768x397.jpg 768w, https:\/\/www.pconstrutora.com.br\/blog\/wp-content\/uploads\/2021\/05\/architecture-project-finishes-and-style-1536x794.jpg 1536w, https:\/\/www.pconstrutora.com.br\/blog\/wp-content\/uploads\/2021\/05\/architecture-project-finishes-and-style-2048x1059.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">A constru\u00e7\u00e3o de um im\u00f3vel \u00e9 norteada por diversas decis\u00f5es, como a escolha de cores, materiais, m\u00e3o-de-obra, profissional respons\u00e1vel e, principalmente, a arquitetura da casa.<\/h2>\n\n\n\n<p>V\u00e1rios fatores devem ser analisados antes da finaliza\u00e7\u00e3o do projeto. A opini\u00e3o dos moradores \u00e9 essencial, mas precisa coincidir com os padr\u00f5es exigidos, al\u00e9m de seguir as normas de seguran\u00e7a.<\/p>\n\n\n\n<p>Antes de iniciar a constru\u00e7\u00e3o de sua casa, confira algumas op\u00e7\u00f5es de arquitetura e escolha a que mais combina com voc\u00ea e sua fam\u00edlia.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>ARQUITETURA MEDITERR\u00c2NEA<\/strong><\/h3>\n\n\n\n<p>Se voc\u00ea deseja ter uma casa com espa\u00e7o amplo, acolhedor, charmoso e cl\u00e1ssico, a arquitetura mediterr\u00e2nea \u00e9 a melhor escolha. <br>Im\u00f3veis que seguem esse par\u00e2metro&nbsp; costumam ter terra\u00e7os nas fachadas, \u00f3timos para reunir a fam\u00edlia e relaxar ap\u00f3s um dia corrido de trabalho.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>ARQUITETURA ESCANDINAVA<\/strong><\/h3>\n\n\n\n<p>Se os detalhes te encantam, a arquitetura escandinava deve estar entre as op\u00e7\u00f5es de escolha. Casas escandinavas utilizam a madeira como principal mat\u00e9ria-prima da constru\u00e7\u00e3o, por isso, \u00e9 necess\u00e1rio um bom projeto de ilumina\u00e7\u00e3o e paisagismo. <br>O grande charme desse tipo de arquitetura est\u00e1 na parte superior das resid\u00eancias, que possuem sacadas r\u00fasticas e acolhedoras.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>ARQUITETURA CL\u00c1SSICA<\/strong><\/h3>\n\n\n\n<p>Um im\u00f3vel com arquitetura cl\u00e1ssica pode ser constru\u00eddo na maioria dos terrenos, pois n\u00e3o exige grandes ajustes e segue uma regra padr\u00e3o nos projetos. <br>Al\u00e9m de pr\u00e1tica, resid\u00eancias com essa estrutura podem abrigar tanto fam\u00edlias pequenas, como grandes.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>ARQUITETURA ECL\u00c9TICA<\/strong><\/h3>\n\n\n\n<p>A arquitetura ecl\u00e9tica \u00e9 ideal para pessoas que desejam mesclar caracter\u00edsticas de outros estilos. Para isso, \u00e9 necess\u00e1rio o aux\u00edlio de um profissional que ir\u00e1 montar o projeto de acordo com as prefer\u00eancias dos moradores.<\/p>\n\n\n\n<p>Alguns optam por utilizar uma fachada cl\u00e1ssica com detalhes escandinavos, por exemplo. H\u00e1 um leque de possibilidades.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>ARQUITETURA TROPICAL<\/strong><\/h3>\n\n\n\n<p>Como o pr\u00f3prio nome indica, a arquitetura tropical \u00e9 ideal para projetos que ser\u00e3o desenvolvidos em locais quentes, como a praia, por exemplo.<\/p>\n\n\n\n<p>A principal caracter\u00edstica desse modelo est\u00e1 nas cores e tons quentes. Arboriza\u00e7\u00e3o, plantas e itens que remetem \u00e0 natureza, tamb\u00e9m s\u00e3o \u00f3timas op\u00e7\u00f5es de decora\u00e7\u00e3o.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>ARQUITETURA ASI\u00c1TICA<\/strong><\/h3>\n\n\n\n<p>Ao contr\u00e1rio da arquitetura tropical, a asi\u00e1tica \u00e9 focada nos tons claros e past\u00e9is.<\/p>\n\n\n\n<p>A sofistica\u00e7\u00e3o est\u00e1 presente em cada detalhe, pois as linhas retas na constru\u00e7\u00e3o, vidros e portas de madeira deslizantes trazem um charme \u00fanico para a casa.<\/p>\n\n\n\n<p>Se voc\u00ea sonha com um im\u00f3vel bem iluminado, essa \u00e9 a op\u00e7\u00e3o ideal. Al\u00e9m do espa\u00e7o receber um toque de aconchego, a luz traz ainda a sensa\u00e7\u00e3o de amplitude.<\/p>\n\n\n\n<p>A boa not\u00edcia \u00e9 que o estilo asi\u00e1tico pode ser constru\u00eddo em terrenos pequenos e com espa\u00e7o reduzido.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>ARQUITETURA AMERICANA<\/strong><\/h3>\n\n\n\n<p>A arquitetura americana \u00e9 uma das mais cobi\u00e7adas por fam\u00edlias que desejam construir a sua casa do zero. Os filmes mostram muito bem cada detalhe desses im\u00f3veis chiques e graciosos.<\/p>\n\n\n\n<p>Esse modelo investe em fachadas na cor branca, muitas colunas e at\u00e9 mesmo terra\u00e7os. Ao contr\u00e1rio do que estamos acostumados a ver nas casas do Brasil, as americanas ficam localizadas no meio do terreno, o que faz com que haja muito espa\u00e7o verde. <br>Normalmente, esses im\u00f3veis tamb\u00e9m n\u00e3o ficam ao lado de outras casas, proporcionando maior privacidade.<\/p>\n\n\n\n<p>No Brasil, o estilo americano \u00e9 indicado para regi\u00f5es do interior,&nbsp; j\u00e1 que o muro baixo n\u00e3o garante seguran\u00e7a para grandes cidades, mas se ainda assim, voc\u00ea sonha com essa op\u00e7\u00e3o, ter um terreno em condom\u00ednio fechado pode ser a solu\u00e7\u00e3o.&nbsp;<\/p>\n\n\n\n<p>Esperamos que este conte\u00fado tenha sido \u00fatil para te atualizar sobre o assunto. Entre em <a href=\"https:\/\/www.pconstrutora.com.br\/#contato\">contato<\/a> com nossa equipe. Vamos te apresentar op\u00e7\u00f5es que seguem o conceito em im\u00f3vel que voc\u00ea deseja.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>J\u00e1 sabe qual a melhor op\u00e7\u00e3o arquitet\u00f4nica para a constru\u00e7\u00e3o da sua casa?! Listamos 7 op\u00e7\u00f5es que voc\u00ea vai amar(a 4 voc\u00ea precisa conhecer).<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27,11,12,1],"tags":[28,30,29],"class_list":["post-153","post","type-post","status-publish","format-standard","hentry","category-dicas","category-dicas-de-imoveis","category-dicas-de-investimento-em-imoveis","category-sem-categoria","tag-arquitetonicos","tag-estilos-de-arquitetura","tag-projetos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Qual a Melhor Op\u00e7\u00e3o de Arquitetura? - Blog Pedreschi - Ribeir\u00e3o Preto<\/title>\n<meta name=\"description\" content=\"J\u00e1 sabe qual a melhor op\u00e7\u00e3o arquitet\u00f4nica para a constru\u00e7\u00e3o da sua casa?! Listamos 7 op\u00e7\u00f5es que voc\u00ea vai amar(a 4 voc\u00ea precisa conhecer).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pconstrutora.com.br\/blog\/arquitetura-melhor-dicas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qual a Melhor Op\u00e7\u00e3o de Arquitetura? - Blog Pedreschi - Ribeir\u00e3o Preto\" \/>\n<meta property=\"og:description\" content=\"J\u00e1 sabe qual a melhor op\u00e7\u00e3o arquitet\u00f4nica para a constru\u00e7\u00e3o da sua casa?! Listamos 7 op\u00e7\u00f5es que voc\u00ea vai amar(a 4 voc\u00ea precisa conhecer).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pconstrutora.com.br\/blog\/arquitetura-melhor-dicas\/\" \/>\n<meta property=\"og:site_name\" content=\"Pedreschi - Blog\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-21T20:56:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-25T20:50:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pconstrutora.com.br\/blog\/wp-content\/uploads\/2021\/05\/architecture-project-finishes-and-style-1024x530.jpg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pconstrutora.com.br\/blog\/arquitetura-melhor-dicas\/\",\"url\":\"https:\/\/www.pconstrutora.com.br\/blog\/arquitetura-melhor-dicas\/\",\"name\":\"Qual a Melhor Op\u00e7\u00e3o de Arquitetura? - Blog Pedreschi - Ribeir\u00e3o Preto\",\"isPartOf\":{\"@id\":\"https:\/\/www.pconstrutora.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.pconstrutora.com.br\/blog\/arquitetura-melhor-dicas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.pconstrutora.com.br\/blog\/arquitetura-melhor-dicas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.pconstrutora.com.br\/blog\/wp-content\/uploads\/2021\/05\/architecture-project-finishes-and-style-1024x530.jpg\",\"datePublished\":\"2021-05-21T20:56:09+00:00\",\"dateModified\":\"2022-02-25T20:50:26+00:00\",\"author\":{\"@id\":\"https:\/\/www.pconstrutora.com.br\/blog\/#\/schema\/person\/1ebd17bcb1d396bcd8685e673fe2ff5a\"},\"description\":\"J\u00e1 sabe qual a melhor op\u00e7\u00e3o arquitet\u00f4nica para a constru\u00e7\u00e3o da sua casa?! Listamos 7 op\u00e7\u00f5es que voc\u00ea vai amar(a 4 voc\u00ea precisa conhecer).\",\"breadcrumb\":{\"@id\":\"https:\/\/www.pconstrutora.com.br\/blog\/arquitetura-melhor-dicas\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pconstrutora.com.br\/blog\/arquitetura-melhor-dicas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pconstrutora.com.br\/blog\/arquitetura-melhor-dicas\/#primaryimage\",\"url\":\"https:\/\/www.pconstrutora.com.br\/blog\/wp-content\/uploads\/2021\/05\/architecture-project-finishes-and-style-1024x530.jpg\",\"contentUrl\":\"https:\/\/www.pconstrutora.com.br\/blog\/wp-content\/uploads\/2021\/05\/architecture-project-finishes-and-style-1024x530.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.pconstrutora.com.br\/blog\/arquitetura-melhor-dicas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.pconstrutora.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estilos arquitet\u00f4nicos para construir uma casa: Qual a melhor op\u00e7\u00e3o?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pconstrutora.com.br\/blog\/#website\",\"url\":\"https:\/\/www.pconstrutora.com.br\/blog\/\",\"name\":\"Pedreschi - Blog\",\"description\":\"S\u00f3 mais um site WordPress\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pconstrutora.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pconstrutora.com.br\/blog\/#\/schema\/person\/1ebd17bcb1d396bcd8685e673fe2ff5a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pconstrutora.com.br\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8a2fa8fe940dfb0084e3a81ad5e4b998?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8a2fa8fe940dfb0084e3a81ad5e4b998?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"http:\/\/localhost\/pw\/2020\/pedreschi-blog\/app\"],\"url\":\"https:\/\/www.pconstrutora.com.br\/blog\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qual a Melhor Op\u00e7\u00e3o de Arquitetura? - Blog Pedreschi - Ribeir\u00e3o Preto","description":"J\u00e1 sabe qual a melhor op\u00e7\u00e3o arquitet\u00f4nica para a constru\u00e7\u00e3o da sua casa?! Listamos 7 op\u00e7\u00f5es que voc\u00ea vai amar(a 4 voc\u00ea precisa conhecer).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pconstrutora.com.br\/blog\/arquitetura-melhor-dicas\/","og_locale":"pt_BR","og_type":"article","og_title":"Qual a Melhor Op\u00e7\u00e3o de Arquitetura? - Blog Pedreschi - Ribeir\u00e3o Preto","og_description":"J\u00e1 sabe qual a melhor op\u00e7\u00e3o arquitet\u00f4nica para a constru\u00e7\u00e3o da sua casa?! Listamos 7 op\u00e7\u00f5es que voc\u00ea vai amar(a 4 voc\u00ea precisa conhecer).","og_url":"https:\/\/www.pconstrutora.com.br\/blog\/arquitetura-melhor-dicas\/","og_site_name":"Pedreschi - Blog","article_published_time":"2021-05-21T20:56:09+00:00","article_modified_time":"2022-02-25T20:50:26+00:00","og_image":[{"url":"https:\/\/www.pconstrutora.com.br\/blog\/wp-content\/uploads\/2021\/05\/architecture-project-finishes-and-style-1024x530.jpg","type":"","width":"","height":""}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pconstrutora.com.br\/blog\/arquitetura-melhor-dicas\/","url":"https:\/\/www.pconstrutora.com.br\/blog\/arquitetura-melhor-dicas\/","name":"Qual a Melhor Op\u00e7\u00e3o de Arquitetura? - Blog Pedreschi - Ribeir\u00e3o Preto","isPartOf":{"@id":"https:\/\/www.pconstrutora.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pconstrutora.com.br\/blog\/arquitetura-melhor-dicas\/#primaryimage"},"image":{"@id":"https:\/\/www.pconstrutora.com.br\/blog\/arquitetura-melhor-dicas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pconstrutora.com.br\/blog\/wp-content\/uploads\/2021\/05\/architecture-project-finishes-and-style-1024x530.jpg","datePublished":"2021-05-21T20:56:09+00:00","dateModified":"2022-02-25T20:50:26+00:00","author":{"@id":"https:\/\/www.pconstrutora.com.br\/blog\/#\/schema\/person\/1ebd17bcb1d396bcd8685e673fe2ff5a"},"description":"J\u00e1 sabe qual a melhor op\u00e7\u00e3o arquitet\u00f4nica para a constru\u00e7\u00e3o da sua casa?! Listamos 7 op\u00e7\u00f5es que voc\u00ea vai amar(a 4 voc\u00ea precisa conhecer).","breadcrumb":{"@id":"https:\/\/www.pconstrutora.com.br\/blog\/arquitetura-melhor-dicas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pconstrutora.com.br\/blog\/arquitetura-melhor-dicas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pconstrutora.com.br\/blog\/arquitetura-melhor-dicas\/#primaryimage","url":"https:\/\/www.pconstrutora.com.br\/blog\/wp-content\/uploads\/2021\/05\/architecture-project-finishes-and-style-1024x530.jpg","contentUrl":"https:\/\/www.pconstrutora.com.br\/blog\/wp-content\/uploads\/2021\/05\/architecture-project-finishes-and-style-1024x530.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.pconstrutora.com.br\/blog\/arquitetura-melhor-dicas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.pconstrutora.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Estilos arquitet\u00f4nicos para construir uma casa: Qual a melhor op\u00e7\u00e3o?"}]},{"@type":"WebSite","@id":"https:\/\/www.pconstrutora.com.br\/blog\/#website","url":"https:\/\/www.pconstrutora.com.br\/blog\/","name":"Pedreschi - Blog","description":"S\u00f3 mais um site WordPress","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pconstrutora.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.pconstrutora.com.br\/blog\/#\/schema\/person\/1ebd17bcb1d396bcd8685e673fe2ff5a","name":"admin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pconstrutora.com.br\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8a2fa8fe940dfb0084e3a81ad5e4b998?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a2fa8fe940dfb0084e3a81ad5e4b998?s=96&d=mm&r=g","caption":"admin"},"sameAs":["http:\/\/localhost\/pw\/2020\/pedreschi-blog\/app"],"url":"https:\/\/www.pconstrutora.com.br\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.pconstrutora.com.br\/blog\/wp-json\/wp\/v2\/posts\/153"}],"collection":[{"href":"https:\/\/www.pconstrutora.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pconstrutora.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pconstrutora.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pconstrutora.com.br\/blog\/wp-json\/wp\/v2\/comments?post=153"}],"version-history":[{"count":7,"href":"https:\/\/www.pconstrutora.com.br\/blog\/wp-json\/wp\/v2\/posts\/153\/revisions"}],"predecessor-version":[{"id":298,"href":"https:\/\/www.pconstrutora.com.br\/blog\/wp-json\/wp\/v2\/posts\/153\/revisions\/298"}],"wp:attachment":[{"href":"https:\/\/www.pconstrutora.com.br\/blog\/wp-json\/wp\/v2\/media?parent=153"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pconstrutora.com.br\/blog\/wp-json\/wp\/v2\/categories?post=153"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pconstrutora.com.br\/blog\/wp-json\/wp\/v2\/tags?post=153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}