{"id":207,"date":"2021-09-13T09:00:00","date_gmt":"2021-09-13T12:00:00","guid":{"rendered":"http:\/\/www.pconstrutora.com.br\/blog\/?p=207"},"modified":"2022-02-25T17:49:00","modified_gmt":"2022-02-25T20:49:00","slug":"10-dicas-para-sua-varanda","status":"publish","type":"post","link":"https:\/\/www.pconstrutora.com.br\/blog\/10-dicas-para-sua-varanda\/","title":{"rendered":"Confira as 10 dicas para decorar sua varanda."},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Saiba como deixar este espa\u00e7o da casa mais aconchegante e com um visual sofisticado.<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.pconstrutora.com.br\/blog\/wp-content\/uploads\/2021\/08\/relaxed-barefooted-girl-white-dress-sitting-chair-balcony-holding-cup-tea-1024x683.jpg\" alt=\"Dicas Para Varanda\" class=\"wp-image-209\" srcset=\"https:\/\/www.pconstrutora.com.br\/blog\/wp-content\/uploads\/2021\/08\/relaxed-barefooted-girl-white-dress-sitting-chair-balcony-holding-cup-tea-1024x683.jpg 1024w, https:\/\/www.pconstrutora.com.br\/blog\/wp-content\/uploads\/2021\/08\/relaxed-barefooted-girl-white-dress-sitting-chair-balcony-holding-cup-tea-300x200.jpg 300w, https:\/\/www.pconstrutora.com.br\/blog\/wp-content\/uploads\/2021\/08\/relaxed-barefooted-girl-white-dress-sitting-chair-balcony-holding-cup-tea-768x512.jpg 768w, https:\/\/www.pconstrutora.com.br\/blog\/wp-content\/uploads\/2021\/08\/relaxed-barefooted-girl-white-dress-sitting-chair-balcony-holding-cup-tea-1536x1024.jpg 1536w, https:\/\/www.pconstrutora.com.br\/blog\/wp-content\/uploads\/2021\/08\/relaxed-barefooted-girl-white-dress-sitting-chair-balcony-holding-cup-tea-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Ultimamente as varandas t\u00eam ganhado destaque nos projetos de casas e apartamentos, especialmente por combinar elementos que trazem inova\u00e7\u00e3o e modernidade, tornando-se em um dos espa\u00e7os mais cobi\u00e7ados nas resid\u00eancias.<\/p>\n\n\n\n<p>Esse espa\u00e7o recebe muita ventila\u00e7\u00e3o e ilumina\u00e7\u00e3o natural, sendo um convite para desfrutar da paisagem, descansar em uma rede por horas ou ser o ponto de encontro para reunir os amigos durante os churrascos ou <em>happy hour<\/em>. Em muitos lares, por exemplo, a cozinha tem sido integrada \u00e0 varanda para oferecer maior comodidade aos moradores e seus convidados.<\/p>\n\n\n\n<p>Para que voc\u00ea se inspire, separamos 10 sugest\u00f5es que v\u00e3o ajudar voc\u00ea a realizar essa transforma\u00e7\u00e3o na sua varanda com muito bom gosto e sofistica\u00e7\u00e3o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Confira as nossas superdicas e m\u00e3os \u00e0 obra.<\/h2>\n\n\n\n<p>1) Utilize a integra\u00e7\u00e3o da varanda ao living.<\/p>\n\n\n\n<p>\u00c9 uma forma de ganhar amplitude dos espa\u00e7os e melhorar a circula\u00e7\u00e3o entre os ambientes. Al\u00e9m disso, menos paredes significa mais luz e ventila\u00e7\u00e3o tamb\u00e9m. Voc\u00ea utilizar revestimentos diferenciados no piso e nas paredes, por exemplos.<\/p>\n\n\n\n<p>2) Construa um cantinho dedicado \u00e0 leitura.<\/p>\n\n\n\n<p>Ao planejar sua nova varanda, reserve espa\u00e7o para um cantinho de leitura, que ofere\u00e7a bastante aconchego e conforto, com uma poltrona ou cadeira, al\u00e9m de mesa de apoio e algumas plantas para tornar o ambiente mais prop\u00edcio \u00e0 leitura.&nbsp;&nbsp;<\/p>\n\n\n\n<p>3) Fa\u00e7a a escolha certa dos m\u00f3veis.<\/p>\n\n\n\n<p>Caso sua varanda seja aberta, opte por pe\u00e7as que possam ficar expostas \u00e0s intemp\u00e9ries da natureza, como o sol e a chuva. Os m\u00f3veis de fibra cumprem bem esse papel e s\u00e3o mais resistentes do que os de madeira, por exemplo, que se desgastam com mais facilidade. Al\u00e9m disso, eles costumam ser mais pesados, o que dificulta sua mudan\u00e7a de local.<\/p>\n\n\n\n<p>4) Coloque bancos confort\u00e1veis para receber os convidados.<\/p>\n\n\n\n<p>Al\u00e9m de pr\u00e1ticos, os bancos costumam ocupar pouco espa\u00e7o e s\u00e3o mais leves. \u00c9 uma boa pedida tamb\u00e9m por permitir uma melhor integra\u00e7\u00e3o entre ambientes, combinando com a decora\u00e7\u00e3o \u00e0 sua volta.<\/p>\n\n\n\n<p>5) Pense no conforto como item principal.<\/p>\n\n\n\n<p>Seja grande ou pequena, a sua varanda deve ser o mais aconchegante poss\u00edvel, para que voc\u00ea possa receber seus convidados com mais descontra\u00e7\u00e3o e informalidade. Por isso, invista em cores claras, sof\u00e1s, poltronas, pufes, redes, almofadas e tapetes para compro o ambiente de forma sutil e agrad\u00e1vel.&nbsp;<\/p>\n\n\n\n<p>6) Invista no paisagismo.<\/p>\n\n\n\n<p>J\u00e1 reparou como as plantas trazem essa sensa\u00e7\u00e3o de frescor e energia? Por isso, nada de deix\u00e1-las de fora na hora de decorar sua varanda, hein? Os jardins verticais economizam espa\u00e7o e, ao mesmo tempo, d\u00e3o um ar de modernidade e s\u00e3o f\u00e1ceis de instalar.<\/p>\n\n\n\n<p>7) Opte por m\u00f3veis planejados.<\/p>\n\n\n\n<p>Independente da \u00e1rea da sua varanda ser grande ou pequena, os m\u00f3veis planejados v\u00e3o facilitar a organiza\u00e7\u00e3o do espa\u00e7o. Al\u00e9m disso, deixam o local mais elegante e funcional para todas as ocasi\u00f5es.<\/p>\n\n\n\n<p>8) Tenha pe\u00e7as multifuncionais.<\/p>\n\n\n\n<p>Bancos que se transformam em um barzinho ou pufes que viram mesa de centro, por exemplo, s\u00e3o excelentes solu\u00e7\u00f5es para espa\u00e7os pequenos. D\u00ea prefer\u00eancia aos m\u00f3veis com rod\u00edzios, pois facilitam o transporte e evitam riscar o piso. Al\u00e9m disso, podem auxiliar na decora\u00e7\u00e3o da sua varanda.&nbsp;<\/p>\n\n\n\n<p>9) Utilize objetos dobr\u00e1veis e f\u00e1ceis de guardar.<\/p>\n\n\n\n<p>Mesas, bancos e cadeiras dobr\u00e1veis s\u00e3o vers\u00e1teis e ajudam a economizar espa\u00e7o, sendo f\u00e1ceis de guardar ou transportar.<\/p>\n\n\n\n<p>10) Menos \u00e9 sempre mais.<\/p>\n\n\n\n<p>Por mais que surjam muitas ideias, \u00e9 importante adequar o espa\u00e7o \u00e0 proposta para n\u00e3o sobrecarregar o local. Pesquise, avalie e sempre pense na funcionalidade para que os elementos combinem e facilitem o seu dia a dia, para que este espa\u00e7o sirva para o seu descanso ou lazer. Apostar na simplicidade \u00e9 uma forma de encontrar equil\u00edbrio e obter um resultado mais satisfat\u00f3rio.&nbsp;<\/p>\n\n\n\n<p>E a\u00ed, gostou dessas dicas oferecidas? Que tal visitar o site da <strong><a href=\"https:\/\/www.pconstrutora.com.br\/#contato\" target=\"_blank\" rel=\"noreferrer noopener\">Pedreschi Construtora<\/a><\/strong> para ver alguns projetos e se inspirar?<\/p>\n\n\n\n<p>Voc\u00ea pode obter mais informa\u00e7\u00f5es em nosso WhatsApp: 16 99344.8655<\/p>\n\n\n\n<p>Ou em nossas redes sociais:<\/p>\n\n\n\n<p><a href=\"http:\/\/www.facebook.com\/pconstrutora\">www.facebook.com\/pconstrutora<\/a><a href=\"http:\/\/www.instagram.com\/pedreschiconstrutora\"> www.instagram.com\/pedreschiconstrutora<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para que voc\u00ea se inspire, separamos 10 sugest\u00f5es que v\u00e3o ajudar voc\u00ea a realizar uma transforma\u00e7\u00e3o na sua varanda com muito bom gosto e sofistica\u00e7\u00e3o.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,27],"tags":[43,77,80,90,20,84,81,79,82,87,89,85,93,83,92,91,19,75,86,94,64,88],"class_list":["post-207","post","type-post","status-publish","format-standard","hentry","category-casa-confortavel","category-dicas","tag-apartamentos","tag-casas","tag-churrasco","tag-conforto","tag-construtora","tag-convidados","tag-cozinha","tag-dicas","tag-happy-hour","tag-iluminacao","tag-iluminacao-natural","tag-lazer","tag-living","tag-moradores","tag-moveis","tag-paisagismo","tag-pedreschi","tag-pedreschi-construtora","tag-residencia","tag-varanda","tag-varandas","tag-ventilacao"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Confira as 10 dicas para decorar sua varanda. - Pedreschi - Blog<\/title>\n<meta name=\"description\" content=\"Ultimamente as varandas t\u00eam ganhado destaque nos projetos de casas e apartamentos, especialmente por combinar elementos que trazem inova\u00e7\u00e3o e modernidade, tornando-se em um dos espa\u00e7os mais cobi\u00e7ados nas resid\u00eancias.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pconstrutora.com.br\/blog\/10-dicas-para-sua-varanda\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Confira as 10 dicas para decorar sua varanda. - Pedreschi - Blog\" \/>\n<meta property=\"og:description\" content=\"Ultimamente as varandas t\u00eam ganhado destaque nos projetos de casas e apartamentos, especialmente por combinar elementos que trazem inova\u00e7\u00e3o e modernidade, tornando-se em um dos espa\u00e7os mais cobi\u00e7ados nas resid\u00eancias.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pconstrutora.com.br\/blog\/10-dicas-para-sua-varanda\/\" \/>\n<meta property=\"og:site_name\" content=\"Pedreschi - Blog\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-13T12:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-25T20:49:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pconstrutora.com.br\/blog\/wp-content\/uploads\/2021\/08\/relaxed-barefooted-girl-white-dress-sitting-chair-balcony-holding-cup-tea-1024x683.jpg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pconstrutora.com.br\/blog\/10-dicas-para-sua-varanda\/\",\"url\":\"https:\/\/www.pconstrutora.com.br\/blog\/10-dicas-para-sua-varanda\/\",\"name\":\"Confira as 10 dicas para decorar sua varanda. - Pedreschi - Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.pconstrutora.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.pconstrutora.com.br\/blog\/10-dicas-para-sua-varanda\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.pconstrutora.com.br\/blog\/10-dicas-para-sua-varanda\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.pconstrutora.com.br\/blog\/wp-content\/uploads\/2021\/08\/relaxed-barefooted-girl-white-dress-sitting-chair-balcony-holding-cup-tea-1024x683.jpg\",\"datePublished\":\"2021-09-13T12:00:00+00:00\",\"dateModified\":\"2022-02-25T20:49:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.pconstrutora.com.br\/blog\/#\/schema\/person\/1ebd17bcb1d396bcd8685e673fe2ff5a\"},\"description\":\"Ultimamente as varandas t\u00eam ganhado destaque nos projetos de casas e apartamentos, especialmente por combinar elementos que trazem inova\u00e7\u00e3o e modernidade, tornando-se em um dos espa\u00e7os mais cobi\u00e7ados nas resid\u00eancias.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.pconstrutora.com.br\/blog\/10-dicas-para-sua-varanda\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pconstrutora.com.br\/blog\/10-dicas-para-sua-varanda\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pconstrutora.com.br\/blog\/10-dicas-para-sua-varanda\/#primaryimage\",\"url\":\"https:\/\/www.pconstrutora.com.br\/blog\/wp-content\/uploads\/2021\/08\/relaxed-barefooted-girl-white-dress-sitting-chair-balcony-holding-cup-tea-1024x683.jpg\",\"contentUrl\":\"https:\/\/www.pconstrutora.com.br\/blog\/wp-content\/uploads\/2021\/08\/relaxed-barefooted-girl-white-dress-sitting-chair-balcony-holding-cup-tea-1024x683.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.pconstrutora.com.br\/blog\/10-dicas-para-sua-varanda\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.pconstrutora.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Confira as 10 dicas para decorar sua varanda.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pconstrutora.com.br\/blog\/#website\",\"url\":\"https:\/\/www.pconstrutora.com.br\/blog\/\",\"name\":\"Pedreschi - Blog\",\"description\":\"S\u00f3 mais um site WordPress\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pconstrutora.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pconstrutora.com.br\/blog\/#\/schema\/person\/1ebd17bcb1d396bcd8685e673fe2ff5a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pconstrutora.com.br\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8a2fa8fe940dfb0084e3a81ad5e4b998?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8a2fa8fe940dfb0084e3a81ad5e4b998?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"http:\/\/localhost\/pw\/2020\/pedreschi-blog\/app\"],\"url\":\"https:\/\/www.pconstrutora.com.br\/blog\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Confira as 10 dicas para decorar sua varanda. - Pedreschi - Blog","description":"Ultimamente as varandas t\u00eam ganhado destaque nos projetos de casas e apartamentos, especialmente por combinar elementos que trazem inova\u00e7\u00e3o e modernidade, tornando-se em um dos espa\u00e7os mais cobi\u00e7ados nas resid\u00eancias.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pconstrutora.com.br\/blog\/10-dicas-para-sua-varanda\/","og_locale":"pt_BR","og_type":"article","og_title":"Confira as 10 dicas para decorar sua varanda. - Pedreschi - Blog","og_description":"Ultimamente as varandas t\u00eam ganhado destaque nos projetos de casas e apartamentos, especialmente por combinar elementos que trazem inova\u00e7\u00e3o e modernidade, tornando-se em um dos espa\u00e7os mais cobi\u00e7ados nas resid\u00eancias.","og_url":"https:\/\/www.pconstrutora.com.br\/blog\/10-dicas-para-sua-varanda\/","og_site_name":"Pedreschi - Blog","article_published_time":"2021-09-13T12:00:00+00:00","article_modified_time":"2022-02-25T20:49:00+00:00","og_image":[{"url":"https:\/\/www.pconstrutora.com.br\/blog\/wp-content\/uploads\/2021\/08\/relaxed-barefooted-girl-white-dress-sitting-chair-balcony-holding-cup-tea-1024x683.jpg","type":"","width":"","height":""}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pconstrutora.com.br\/blog\/10-dicas-para-sua-varanda\/","url":"https:\/\/www.pconstrutora.com.br\/blog\/10-dicas-para-sua-varanda\/","name":"Confira as 10 dicas para decorar sua varanda. - Pedreschi - Blog","isPartOf":{"@id":"https:\/\/www.pconstrutora.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pconstrutora.com.br\/blog\/10-dicas-para-sua-varanda\/#primaryimage"},"image":{"@id":"https:\/\/www.pconstrutora.com.br\/blog\/10-dicas-para-sua-varanda\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pconstrutora.com.br\/blog\/wp-content\/uploads\/2021\/08\/relaxed-barefooted-girl-white-dress-sitting-chair-balcony-holding-cup-tea-1024x683.jpg","datePublished":"2021-09-13T12:00:00+00:00","dateModified":"2022-02-25T20:49:00+00:00","author":{"@id":"https:\/\/www.pconstrutora.com.br\/blog\/#\/schema\/person\/1ebd17bcb1d396bcd8685e673fe2ff5a"},"description":"Ultimamente as varandas t\u00eam ganhado destaque nos projetos de casas e apartamentos, especialmente por combinar elementos que trazem inova\u00e7\u00e3o e modernidade, tornando-se em um dos espa\u00e7os mais cobi\u00e7ados nas resid\u00eancias.","breadcrumb":{"@id":"https:\/\/www.pconstrutora.com.br\/blog\/10-dicas-para-sua-varanda\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pconstrutora.com.br\/blog\/10-dicas-para-sua-varanda\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pconstrutora.com.br\/blog\/10-dicas-para-sua-varanda\/#primaryimage","url":"https:\/\/www.pconstrutora.com.br\/blog\/wp-content\/uploads\/2021\/08\/relaxed-barefooted-girl-white-dress-sitting-chair-balcony-holding-cup-tea-1024x683.jpg","contentUrl":"https:\/\/www.pconstrutora.com.br\/blog\/wp-content\/uploads\/2021\/08\/relaxed-barefooted-girl-white-dress-sitting-chair-balcony-holding-cup-tea-1024x683.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.pconstrutora.com.br\/blog\/10-dicas-para-sua-varanda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.pconstrutora.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Confira as 10 dicas para decorar sua varanda."}]},{"@type":"WebSite","@id":"https:\/\/www.pconstrutora.com.br\/blog\/#website","url":"https:\/\/www.pconstrutora.com.br\/blog\/","name":"Pedreschi - Blog","description":"S\u00f3 mais um site WordPress","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pconstrutora.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.pconstrutora.com.br\/blog\/#\/schema\/person\/1ebd17bcb1d396bcd8685e673fe2ff5a","name":"admin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pconstrutora.com.br\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8a2fa8fe940dfb0084e3a81ad5e4b998?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a2fa8fe940dfb0084e3a81ad5e4b998?s=96&d=mm&r=g","caption":"admin"},"sameAs":["http:\/\/localhost\/pw\/2020\/pedreschi-blog\/app"],"url":"https:\/\/www.pconstrutora.com.br\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.pconstrutora.com.br\/blog\/wp-json\/wp\/v2\/posts\/207"}],"collection":[{"href":"https:\/\/www.pconstrutora.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pconstrutora.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pconstrutora.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pconstrutora.com.br\/blog\/wp-json\/wp\/v2\/comments?post=207"}],"version-history":[{"count":13,"href":"https:\/\/www.pconstrutora.com.br\/blog\/wp-json\/wp\/v2\/posts\/207\/revisions"}],"predecessor-version":[{"id":295,"href":"https:\/\/www.pconstrutora.com.br\/blog\/wp-json\/wp\/v2\/posts\/207\/revisions\/295"}],"wp:attachment":[{"href":"https:\/\/www.pconstrutora.com.br\/blog\/wp-json\/wp\/v2\/media?parent=207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pconstrutora.com.br\/blog\/wp-json\/wp\/v2\/categories?post=207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pconstrutora.com.br\/blog\/wp-json\/wp\/v2\/tags?post=207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}