{"id":501,"date":"2024-05-07T13:52:58","date_gmt":"2024-05-07T16:52:58","guid":{"rendered":"https:\/\/www.pconstrutora.com.br\/blog\/?p=501"},"modified":"2024-05-07T13:58:55","modified_gmt":"2024-05-07T16:58:55","slug":"por-que-investir-em-um-coliving","status":"publish","type":"post","link":"https:\/\/www.pconstrutora.com.br\/blog\/por-que-investir-em-um-coliving\/","title":{"rendered":"Por que investir em um coliving?"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.pconstrutora.com.br\/blog\/wp-content\/uploads\/2024\/05\/Fotos-PConstrutora-1-1024x1024.png\" alt=\"\" class=\"wp-image-506\" style=\"width:321px;height:auto\"\/><\/figure>\n\n\n\n<p>O coliving emergiu como uma tend\u00eancia inovadora no setor imobili\u00e1rio, oferecendo abordagem \u00fanica para a vida compartilhada. E j\u00e1 est\u00e1 a\u00ed um dos motivos do <strong>por que investir em um coliving<\/strong>.<\/p>\n\n\n\n<p>Com a crescente popularidade entre jovens profissionais, n\u00f4mades digitais e estudantes, este novo estilo est\u00e1 redefinindo a forma como as pessoas encaram a moradia e neste conte\u00fado desenvolvido pela Pedreschi, vamos explorar as raz\u00f5es pelas quais investir neste tipo de moradia e ajudar voc\u00ea a descobrir as respostas para a pergunta que n\u00e3o quer calar: <strong>por que investir em um coliving<\/strong>? J\u00e1 te adiantamos que trata-se de uma ideia bastante inteligente. Ent\u00e3o, fica at\u00e9 o final deste conte\u00fado e descubra tudo, afinal, muito mais do que simplesmente compartilhar um espa\u00e7o habitacional, trata-se de uma filosofia de vida baseada na comunidade, colabora\u00e7\u00e3o e conex\u00f5es significativas. Originado em ambientes urbanos densos, como S\u00e3o Francisco e Nova York, o coliving ganhou popularidade globalmente devido \u00e0 sua abordagem inovadora e adapt\u00e1vel \u00e0 vida moderna.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Vantagens do Coliving<\/h2>\n\n\n\n<p>Para entender de vez <strong>por que investir em um coliving<\/strong>, \u00e9 necess\u00e1rio ter compreens\u00e3o das vantagens que este estilo de moradia oferece, n\u00e3o \u00e9 mesmo? Por isto, vamos abordar, abaixo, algumas das principais:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><em>Compartilhamento de espa\u00e7os e recursos:<\/em> Em um ambiente de coliving, os residentes compartilham n\u00e3o apenas o espa\u00e7o f\u00edsico, mas tamb\u00e9m recursos como cozinhas, salas de estar e \u00e1reas de trabalho. Isso n\u00e3o s\u00f3 reduz os custos individuais, mas tamb\u00e9m promove um estilo de vida mais sustent\u00e1vel.<\/li>\n\n\n\n<li><em>Comunidade e networking:<\/em> Este novo estilo de moradia incentiva a forma\u00e7\u00e3o de comunidades coesas, onde os residentes podem se conectar, colaborar e apoiar uns aos outros. Essa rede de suporte n\u00e3o s\u00f3 enriquece a vida social, mas tamb\u00e9m oferece oportunidades profissionais e de networking.<\/li>\n\n\n\n<li>Flexibilidade e conveni\u00eancia: Quando voc\u00ea se perguntar <strong>por que investir em um coliving<\/strong>, lembre-se que uma das vantagens \u00e9 a flexibilidade, afinal, \u00e9 assim que funcionam os contratos de loca\u00e7\u00e3o, al\u00e9m de ampla gama de comodidades dispon\u00edveis, o coliving oferece uma solu\u00e7\u00e3o conveniente para pessoas que buscam uma experi\u00eancia de moradia sem complica\u00e7\u00f5es. Essa flexibilidade \u00e9 especialmente atraente para profissionais que precisam se deslocar com frequ\u00eancia.<\/li>\n\n\n\n<li><em>Custos compartilhados:<\/em> Ao dividir o aluguel e as despesas comunit\u00e1rias, os residentes do coliving podem desfrutar de custos significativamente mais baixos em compara\u00e7\u00e3o com viver sozinho.\u00a0<\/li>\n\n\n\n<li><em>Redu\u00e7\u00e3o de despesas individuais:<\/em> Al\u00e9m do aluguel compartilhado, o coliving tamb\u00e9m oferece economias em despesas como internet, limpeza e manuten\u00e7\u00e3o, resultando em uma redu\u00e7\u00e3o geral nos custos de vida.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Aspectos sociais e comunit\u00e1rios<\/h2>\n\n\n\n<p>Agora voc\u00ea j\u00e1 sabe mais sobre as vantagens de se incluir neste novo estilo de vida relacionado \u00e0 moradia e tamb\u00e9m j\u00e1 entendeu um pouco mais sobre <strong>por que investir em um coliving<\/strong>. Agora, vamos te apresentar que o coliving oferece uma oportunidade \u00fanica para fortalecer la\u00e7os interpessoais e participar de uma comunidade vibrante.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Fortalecimento de la\u00e7os interpessoais<\/h3>\n\n\n\n<p>Viver em um ambiente de coliving promove intera\u00e7\u00f5es sociais significativas, ajudando os residentes a construir relacionamentos s\u00f3lidos e duradouros.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Inclus\u00e3o e diversidade<\/h3>\n\n\n\n<p>Os espa\u00e7os de coliving geralmente atraem pessoas de diferentes origens e culturas, criando um ambiente inclusivo e diversificado, onde as diferen\u00e7as s\u00e3o celebradas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Por que investir em um coliving? A resposta est\u00e1 na qualidade de vida<\/h2>\n\n\n\n<p>O coliving pode ter um impacto positivo significativo na qualidade de vida dos seus residentes, proporcionando bem-estar emocional e acesso a servi\u00e7os e comodidades.&nbsp;<\/p>\n\n\n\n<p>Quando se fala em bem estar, principalmente no quesito emocional, diz-se respeito ao senso de comunidade e apoio m\u00fatuo, que no coliving contribui para a redu\u00e7\u00e3o do isolamento social.<\/p>\n\n\n\n<p>Al\u00e9m do mais, muitos espa\u00e7os de coliving oferecem uma variedade de servi\u00e7os e comodidades, como academia, espa\u00e7os de trabalho compartilhados e eventos sociais, que contribuem para uma vida mais confort\u00e1vel e conveniente.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Tend\u00eancias do mercado imobili\u00e1rio<\/h2>\n\n\n\n<p>O mercado de coliving est\u00e1 experimentando um crescimento significativo devido \u00e0 sua crescente demanda e adaptabilidade \u00e0s necessidades dos moradores modernos. Empreendimentos de coliving est\u00e3o se expandindo em todo o mundo, refletindo uma mudan\u00e7a na mentalidade das pessoas em rela\u00e7\u00e3o \u00e0 moradia e ao estilo de vida.<\/p>\n\n\n\n<p>Al\u00e9m do mais, com a natureza vol\u00e1til do mercado de trabalho e a crescente tend\u00eancia de trabalho remoto, a demanda por espa\u00e7os de coliving flex\u00edveis est\u00e1 em ascens\u00e3o. Est\u00e1 a\u00ed, ent\u00e3o, mais uma resposta para voc\u00ea descobrir <strong>por que investir em um coliving<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Perfil dos residentes<\/h2>\n\n\n\n<p>O coliving atrai uma ampla gama de residentes, cada um com suas pr\u00f3prias necessidades e prefer\u00eancias. O p\u00fablico-alvo pode variar, mas os caminhos por quem procura este tipo de moradia s\u00e3o os mesmos. Para quem busca entender <strong>por que investir em um coliving <\/strong>e quer saber mais sobre o perfil dos residentes, se incluem neste pacote os jovens profissionais, n\u00f4mades digitais e estudantes, por exemplo. Abaixo, explicamos melhor:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Jovens profissionais<\/h3>\n\n\n\n<p>Profissionais jovens muitas vezes optam pelo coliving devido \u00e0 sua conveni\u00eancia, estilo de vida socialmente ativo e oportunidades de networking.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">N\u00f4mades digitais<\/h3>\n\n\n\n<p>Para n\u00f4mades digitais e freelancers, o coliving oferece n\u00e3o apenas um espa\u00e7o para morar, mas tamb\u00e9m uma comunidade de apoio e inspira\u00e7\u00e3o.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Estudantes<\/h3>\n\n\n\n<p>Estudantes universit\u00e1rios encontram no coliving uma alternativa acess\u00edvel e socialmente envolvente \u00e0 moradia tradicional no campus.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Impacto ambiental<\/h2>\n\n\n\n<p>O coliving promove um estilo de vida mais sustent\u00e1vel e consciente dos recursos. E este \u00e9 um detalhe importante a se considerar quando se busca um novo estilo de moradia.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><em>Uso eficiente de recursos:<\/em> Ao compartilhar espa\u00e7os e recursos, o coliving reduz o desperd\u00edcio e promove um uso mais eficiente dos recursos dispon\u00edveis.<\/li>\n\n\n\n<li><em>Redu\u00e7\u00e3o da pegada de carbono:<\/em> A concentra\u00e7\u00e3o de pessoas em espa\u00e7os de coliving contribui para uma pegada de carbono mais baixa em compara\u00e7\u00e3o com resid\u00eancias individuais.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Coliving no contexto global<\/h2>\n\n\n\n<p>Este conceito, \u00e9 importante esclarecer, est\u00e1 ganhando popularidade em todo o mundo, com uma variedade de espa\u00e7os \u00fanicos surgindo em diversas localidades, aumentando os interesses por descobrir <strong>por que investir em um coliving<\/strong>.<\/p>\n\n\n\n<p>De comunidades urbanas a retiros rurais, existem in\u00fameros exemplos inspiradores de espa\u00e7os de coliving que atendem a uma variedade de estilos de vida e prefer\u00eancias.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Como escolher um Coliving?<\/h2>\n\n\n\n<p>Al\u00e9m de entender <strong>por que investir em um coliving<\/strong>, tamb\u00e9m \u00e9 necess\u00e1rio saber como fazer a escolha certa. Ao optar por um espa\u00e7o de coliving, \u00e9 importante considerar uma variedade de fatores para garantir uma experi\u00eancia satisfat\u00f3ria, como por exemplo:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Localiza\u00e7\u00e3o e acessibilidade<\/h3>\n\n\n\n<p>A localiza\u00e7\u00e3o do coliving em rela\u00e7\u00e3o ao transporte p\u00fablico, servi\u00e7os e \u00e1reas de interesse \u00e9 um aspecto crucial a ser considerado.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Comodidades oferecidas<\/h3>\n\n\n\n<p>A variedade e qualidade das comodidades dispon\u00edveis no coliving, como espa\u00e7os de trabalho, \u00e1reas de lazer e servi\u00e7os de limpeza, podem influenciar significativamente a experi\u00eancia do residente.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Cultura e valores da comunidade<\/h3>\n\n\n\n<p>A cultura e os valores da comunidade de coliving devem estar alinhados com as prefer\u00eancias e estilo de vida do residente, promovendo uma experi\u00eancia de moradia positiva e enriquecedora.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Por que investir em um coliving? Fale com quem entende!<\/h2>\n\n\n\n<p>N\u00e3o perca mais tempo se fazendo perguntas sobre o porque investir em um ou outro tipo de moradia. Tire suas d\u00favidas com quem mais entende do assunto e est\u00e1 por dentro das tend\u00eancias deste mercado. Preencha o formul\u00e1rio abaixo e fale com o time da Pedreschi, conhe\u00e7a suas op\u00e7\u00f5es de moradia e infraestrutura e fa\u00e7a a escolha certa.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O coliving emergiu como uma tend\u00eancia inovadora no setor imobili\u00e1rio, oferecendo abordagem \u00fanica para a vida compartilhada. E j\u00e1 est\u00e1 a\u00ed um dos motivos do por que investir em um coliving. Com a crescente popularidade entre jovens profissionais, n\u00f4mades digitais e estudantes, este novo estilo est\u00e1 redefinindo a forma como as pessoas encaram a moradia [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-501","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Por que investir em um coliving? - Pedreschi - Blog<\/title>\n<meta name=\"description\" content=\"Descubra por que investir em um coliving: uma abordagem inovadora para uma vida compartilhada.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pconstrutora.com.br\/blog\/por-que-investir-em-um-coliving\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Por que investir em um coliving? - Pedreschi - Blog\" \/>\n<meta property=\"og:description\" content=\"Descubra por que investir em um coliving: uma abordagem inovadora para uma vida compartilhada.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pconstrutora.com.br\/blog\/por-que-investir-em-um-coliving\/\" \/>\n<meta property=\"og:site_name\" content=\"Pedreschi - Blog\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-07T16:52:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-07T16:58:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pconstrutora.com.br\/blog\/wp-content\/uploads\/2024\/05\/Fotos-PConstrutora-1-1024x1024.png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pconstrutora.com.br\/blog\/por-que-investir-em-um-coliving\/\",\"url\":\"https:\/\/www.pconstrutora.com.br\/blog\/por-que-investir-em-um-coliving\/\",\"name\":\"Por que investir em um coliving? - Pedreschi - Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.pconstrutora.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.pconstrutora.com.br\/blog\/por-que-investir-em-um-coliving\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.pconstrutora.com.br\/blog\/por-que-investir-em-um-coliving\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.pconstrutora.com.br\/blog\/wp-content\/uploads\/2024\/05\/Fotos-PConstrutora-1-1024x1024.png\",\"datePublished\":\"2024-05-07T16:52:58+00:00\",\"dateModified\":\"2024-05-07T16:58:55+00:00\",\"author\":{\"@id\":\"https:\/\/www.pconstrutora.com.br\/blog\/#\/schema\/person\/1ebd17bcb1d396bcd8685e673fe2ff5a\"},\"description\":\"Descubra por que investir em um coliving: uma abordagem inovadora para uma vida compartilhada.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.pconstrutora.com.br\/blog\/por-que-investir-em-um-coliving\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pconstrutora.com.br\/blog\/por-que-investir-em-um-coliving\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pconstrutora.com.br\/blog\/por-que-investir-em-um-coliving\/#primaryimage\",\"url\":\"https:\/\/www.pconstrutora.com.br\/blog\/wp-content\/uploads\/2024\/05\/Fotos-PConstrutora-1-e1715101113816.png\",\"contentUrl\":\"https:\/\/www.pconstrutora.com.br\/blog\/wp-content\/uploads\/2024\/05\/Fotos-PConstrutora-1-e1715101113816.png\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.pconstrutora.com.br\/blog\/por-que-investir-em-um-coliving\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.pconstrutora.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Por que investir em um coliving?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pconstrutora.com.br\/blog\/#website\",\"url\":\"https:\/\/www.pconstrutora.com.br\/blog\/\",\"name\":\"Pedreschi - Blog\",\"description\":\"S\u00f3 mais um site WordPress\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pconstrutora.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pconstrutora.com.br\/blog\/#\/schema\/person\/1ebd17bcb1d396bcd8685e673fe2ff5a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pconstrutora.com.br\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8a2fa8fe940dfb0084e3a81ad5e4b998?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8a2fa8fe940dfb0084e3a81ad5e4b998?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"http:\/\/localhost\/pw\/2020\/pedreschi-blog\/app\"],\"url\":\"https:\/\/www.pconstrutora.com.br\/blog\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Por que investir em um coliving? - Pedreschi - Blog","description":"Descubra por que investir em um coliving: uma abordagem inovadora para uma vida compartilhada.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pconstrutora.com.br\/blog\/por-que-investir-em-um-coliving\/","og_locale":"pt_BR","og_type":"article","og_title":"Por que investir em um coliving? - Pedreschi - Blog","og_description":"Descubra por que investir em um coliving: uma abordagem inovadora para uma vida compartilhada.","og_url":"https:\/\/www.pconstrutora.com.br\/blog\/por-que-investir-em-um-coliving\/","og_site_name":"Pedreschi - Blog","article_published_time":"2024-05-07T16:52:58+00:00","article_modified_time":"2024-05-07T16:58:55+00:00","og_image":[{"url":"https:\/\/www.pconstrutora.com.br\/blog\/wp-content\/uploads\/2024\/05\/Fotos-PConstrutora-1-1024x1024.png","type":"","width":"","height":""}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pconstrutora.com.br\/blog\/por-que-investir-em-um-coliving\/","url":"https:\/\/www.pconstrutora.com.br\/blog\/por-que-investir-em-um-coliving\/","name":"Por que investir em um coliving? - Pedreschi - Blog","isPartOf":{"@id":"https:\/\/www.pconstrutora.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pconstrutora.com.br\/blog\/por-que-investir-em-um-coliving\/#primaryimage"},"image":{"@id":"https:\/\/www.pconstrutora.com.br\/blog\/por-que-investir-em-um-coliving\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pconstrutora.com.br\/blog\/wp-content\/uploads\/2024\/05\/Fotos-PConstrutora-1-1024x1024.png","datePublished":"2024-05-07T16:52:58+00:00","dateModified":"2024-05-07T16:58:55+00:00","author":{"@id":"https:\/\/www.pconstrutora.com.br\/blog\/#\/schema\/person\/1ebd17bcb1d396bcd8685e673fe2ff5a"},"description":"Descubra por que investir em um coliving: uma abordagem inovadora para uma vida compartilhada.","breadcrumb":{"@id":"https:\/\/www.pconstrutora.com.br\/blog\/por-que-investir-em-um-coliving\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pconstrutora.com.br\/blog\/por-que-investir-em-um-coliving\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pconstrutora.com.br\/blog\/por-que-investir-em-um-coliving\/#primaryimage","url":"https:\/\/www.pconstrutora.com.br\/blog\/wp-content\/uploads\/2024\/05\/Fotos-PConstrutora-1-e1715101113816.png","contentUrl":"https:\/\/www.pconstrutora.com.br\/blog\/wp-content\/uploads\/2024\/05\/Fotos-PConstrutora-1-e1715101113816.png","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/www.pconstrutora.com.br\/blog\/por-que-investir-em-um-coliving\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.pconstrutora.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Por que investir em um coliving?"}]},{"@type":"WebSite","@id":"https:\/\/www.pconstrutora.com.br\/blog\/#website","url":"https:\/\/www.pconstrutora.com.br\/blog\/","name":"Pedreschi - Blog","description":"S\u00f3 mais um site WordPress","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pconstrutora.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.pconstrutora.com.br\/blog\/#\/schema\/person\/1ebd17bcb1d396bcd8685e673fe2ff5a","name":"admin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pconstrutora.com.br\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8a2fa8fe940dfb0084e3a81ad5e4b998?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a2fa8fe940dfb0084e3a81ad5e4b998?s=96&d=mm&r=g","caption":"admin"},"sameAs":["http:\/\/localhost\/pw\/2020\/pedreschi-blog\/app"],"url":"https:\/\/www.pconstrutora.com.br\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.pconstrutora.com.br\/blog\/wp-json\/wp\/v2\/posts\/501"}],"collection":[{"href":"https:\/\/www.pconstrutora.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pconstrutora.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pconstrutora.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pconstrutora.com.br\/blog\/wp-json\/wp\/v2\/comments?post=501"}],"version-history":[{"count":8,"href":"https:\/\/www.pconstrutora.com.br\/blog\/wp-json\/wp\/v2\/posts\/501\/revisions"}],"predecessor-version":[{"id":512,"href":"https:\/\/www.pconstrutora.com.br\/blog\/wp-json\/wp\/v2\/posts\/501\/revisions\/512"}],"wp:attachment":[{"href":"https:\/\/www.pconstrutora.com.br\/blog\/wp-json\/wp\/v2\/media?parent=501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pconstrutora.com.br\/blog\/wp-json\/wp\/v2\/categories?post=501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pconstrutora.com.br\/blog\/wp-json\/wp\/v2\/tags?post=501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}